{"id":31974,"date":"2024-12-31T08:00:14","date_gmt":"2024-12-31T07:00:14","guid":{"rendered":"https:\/\/groupe-canopee.fr\/?p=31974"},"modified":"2025-01-06T12:37:26","modified_gmt":"2025-01-06T11:37:26","slug":"point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance","status":"publish","type":"post","link":"https:\/\/groupe-canopee.fr\/en\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/","title":{"rendered":"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"31974\" class=\"elementor elementor-31974\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23008d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23008d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2a3fb1\" data-id=\"e2a3fb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea081d9 elementor-widget elementor-widget-text-editor\" data-id=\"ea081d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Depuis mai 2024, fin de l\u2019aide exceptionnelle pour l\u2019embauche en contrat de professionnalisation\u00a0<\/h2><p>Mise en place en 2020, l\u2019aide exceptionnelle \u00e0 l\u2019embauche de salari\u00e9s en contrat de professionnalisation a \u00e9t\u00e9 supprim\u00e9e par d\u00e9cret le 27 avril 2024. La mesure prend effet d\u00e8s le 1\u1d49\u02b3 mai 2024. \u00c0 compter de cette date, seule l\u2019aide \u00e0 l\u2019embauche de contrat d\u2019apprentissage est maintenue.<br \/>L\u2019OPCO peut n\u00e9anmoins toujours financer les co\u00fbts de formation en alternance. Les taux de prise en charges varient d\u2019une branche professionnelle \u00e0 une autres.<\/p><h3>Diminution de l\u2019aide exceptionnelle \u00e0\u00a0l\u2019apprentissage \u00e0\u00a0compter du\u00a01er\u00a0janvier 2025<\/h3><p>Pour rappel, cette aide exceptionnelle de 6\u2009000\u2009euros pour la premi\u00e8re ann\u00e9e d\u2019ex\u00e9cution du contrat d\u2019apprentissage concernait l\u2019embauche d\u2019apprentis pr\u00e9parant un dipl\u00f4me au plus de niveau 7 (bac\u2009+\u20095)\u00a0et\u00a0visait toutes les entreprises, quel que soit leur effectif.<\/p><p>Le projet\u00a0de loi de finances pour 2025 pr\u00e9voyait une baisse des aides \u00e0 l\u2019embauche des apprentis. Il n\u2019\u00e9tait cependant pas pr\u00e9vu de supprimer cette aide, mais de la r\u00e9duire\u00a0et\/ou d\u2019en moduler le montant en fonction du niveau de qualification de l\u2019apprenti\u00a0et\u00a0de la taille de l\u2019entreprise par d\u00e9cret.<\/p><p><strong>Le d\u00e9cret fixant le principe de cette aide aux employeurs arrive \u00e0 \u00e9ch\u00e9ance le 31 d\u00e9cembre 2024.<br \/>Compte tenu de la d\u00e9mission du Gouvernement \u00e0 la suite de la censure du projet de loi de financement de la s\u00e9curit\u00e9 sociale, le gouvernement a indiqu\u00e9 reconduira par d\u00e9cret une aide pour les employeurs embauchant des apprentis.<\/strong><\/p><p><strong>Elle sera d\u2019un montant de 5 000 \u20ac pour l\u2019embauche d\u2019un apprenti au titre de la seule premi\u00e8re ann\u00e9e du contrat pour les entreprises de moins de 250 salari\u00e9s et de 2 000 \u20ac pour les autres entreprises.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s plusieurs ann\u00e9es caract\u00e9ris\u00e9es par des mesures en faveur de l\u2019alternance, l\u2019ann\u00e9e 2024 se distingue par une r\u00e9duction des aides financi\u00e8res allou\u00e9es.<\/p>","protected":false},"author":1,"featured_media":31977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-31974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-social"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance - Groupe Canop\u00e9e<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/groupe-canopee.fr\/en\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance - Groupe Canop\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s plusieurs ann\u00e9es caract\u00e9ris\u00e9es par des mesures en faveur de l\u2019alternance, l\u2019ann\u00e9e 2024 se distingue par une r\u00e9duction des aides financi\u00e8res allou\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/groupe-canopee.fr\/en\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe Canop\u00e9e\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-31T07:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-06T11:37:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/groupe-canopee.fr\/wp-content\/uploads\/2024\/12\/aides-financieres-alternance.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"service@yellowtie.fr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"service@yellowtie.fr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/\"},\"author\":{\"name\":\"service@yellowtie.fr\",\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/#\\\/schema\\\/person\\\/467a47dbde5188b6358d37e5e917a6c2\"},\"headline\":\"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance\",\"datePublished\":\"2024-12-31T07:00:14+00:00\",\"dateModified\":\"2025-01-06T11:37:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/\"},\"wordCount\":311,\"publisher\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/groupe-canopee.fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/aides-financieres-alternance.jpg\",\"articleSection\":[\"Social\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/\",\"url\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/\",\"name\":\"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance - Groupe Canop\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/groupe-canopee.fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/aides-financieres-alternance.jpg\",\"datePublished\":\"2024-12-31T07:00:14+00:00\",\"dateModified\":\"2025-01-06T11:37:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/groupe-canopee.fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/aides-financieres-alternance.jpg\",\"contentUrl\":\"https:\\\/\\\/groupe-canopee.fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/aides-financieres-alternance.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/groupe-canopee.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/#website\",\"url\":\"https:\\\/\\\/groupe-canopee.fr\\\/\",\"name\":\"Groupe Canop\u00e9e\",\"description\":\"Expertise comptable &amp; conseil\",\"publisher\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/groupe-canopee.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/#organization\",\"name\":\"Groupe Canop\u00e9e\",\"url\":\"https:\\\/\\\/groupe-canopee.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/groupe-canopee.fr\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/canopee-seule-696.jpg\",\"contentUrl\":\"https:\\\/\\\/groupe-canopee.fr\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/canopee-seule-696.jpg\",\"width\":696,\"height\":696,\"caption\":\"Groupe Canop\u00e9e\"},\"image\":{\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/canope-groupe\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/groupe-canopee.fr\\\/#\\\/schema\\\/person\\\/467a47dbde5188b6358d37e5e917a6c2\",\"name\":\"service@yellowtie.fr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b21d0faaff558c379e02a325d9707f1df9389df7db07c39d54ae8e8a21050d62?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b21d0faaff558c379e02a325d9707f1df9389df7db07c39d54ae8e8a21050d62?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b21d0faaff558c379e02a325d9707f1df9389df7db07c39d54ae8e8a21050d62?s=96&d=mm&r=g\",\"caption\":\"service@yellowtie.fr\"},\"sameAs\":[\"https:\\\/\\\/groupe-canopee.yellowtie.fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance - Groupe Canop\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/groupe-canopee.fr\/en\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/","og_locale":"en_GB","og_type":"article","og_title":"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance - Groupe Canop\u00e9e","og_description":"Apr\u00e8s plusieurs ann\u00e9es caract\u00e9ris\u00e9es par des mesures en faveur de l\u2019alternance, l\u2019ann\u00e9e 2024 se distingue par une r\u00e9duction des aides financi\u00e8res allou\u00e9es.","og_url":"https:\/\/groupe-canopee.fr\/en\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/","og_site_name":"Groupe Canop\u00e9e","article_published_time":"2024-12-31T07:00:14+00:00","article_modified_time":"2025-01-06T11:37:26+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/groupe-canopee.fr\/wp-content\/uploads\/2024\/12\/aides-financieres-alternance.jpg","type":"image\/jpeg"}],"author":"service@yellowtie.fr","twitter_card":"summary_large_image","twitter_misc":{"Written by":"service@yellowtie.fr","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/#article","isPartOf":{"@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/"},"author":{"name":"service@yellowtie.fr","@id":"https:\/\/groupe-canopee.fr\/#\/schema\/person\/467a47dbde5188b6358d37e5e917a6c2"},"headline":"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance","datePublished":"2024-12-31T07:00:14+00:00","dateModified":"2025-01-06T11:37:26+00:00","mainEntityOfPage":{"@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/"},"wordCount":311,"publisher":{"@id":"https:\/\/groupe-canopee.fr\/#organization"},"image":{"@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/#primaryimage"},"thumbnailUrl":"https:\/\/groupe-canopee.fr\/wp-content\/uploads\/2024\/12\/aides-financieres-alternance.jpg","articleSection":["Social"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/","url":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/","name":"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance - Groupe Canop\u00e9e","isPartOf":{"@id":"https:\/\/groupe-canopee.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/#primaryimage"},"image":{"@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/#primaryimage"},"thumbnailUrl":"https:\/\/groupe-canopee.fr\/wp-content\/uploads\/2024\/12\/aides-financieres-alternance.jpg","datePublished":"2024-12-31T07:00:14+00:00","dateModified":"2025-01-06T11:37:26+00:00","breadcrumb":{"@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/#primaryimage","url":"https:\/\/groupe-canopee.fr\/wp-content\/uploads\/2024\/12\/aides-financieres-alternance.jpg","contentUrl":"https:\/\/groupe-canopee.fr\/wp-content\/uploads\/2024\/12\/aides-financieres-alternance.jpg","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/groupe-canopee.fr\/point-detape-sur-les-aides-financieres-pour-les-contrats-dalternance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/groupe-canopee.fr\/"},{"@type":"ListItem","position":2,"name":"Point d\u2019\u00e9tape sur les aides financi\u00e8res pour les contrats d\u2019alternance"}]},{"@type":"WebSite","@id":"https:\/\/groupe-canopee.fr\/#website","url":"https:\/\/groupe-canopee.fr\/","name":"Groupe Canop\u00e9e","description":"Expertise comptable &amp; conseil","publisher":{"@id":"https:\/\/groupe-canopee.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/groupe-canopee.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/groupe-canopee.fr\/#organization","name":"Groupe Canop\u00e9e","url":"https:\/\/groupe-canopee.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/groupe-canopee.fr\/#\/schema\/logo\/image\/","url":"https:\/\/groupe-canopee.fr\/wp-content\/uploads\/2024\/11\/canopee-seule-696.jpg","contentUrl":"https:\/\/groupe-canopee.fr\/wp-content\/uploads\/2024\/11\/canopee-seule-696.jpg","width":696,"height":696,"caption":"Groupe Canop\u00e9e"},"image":{"@id":"https:\/\/groupe-canopee.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr.linkedin.com\/company\/canope-groupe"]},{"@type":"Person","@id":"https:\/\/groupe-canopee.fr\/#\/schema\/person\/467a47dbde5188b6358d37e5e917a6c2","name":"service@yellowtie.fr","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/b21d0faaff558c379e02a325d9707f1df9389df7db07c39d54ae8e8a21050d62?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b21d0faaff558c379e02a325d9707f1df9389df7db07c39d54ae8e8a21050d62?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b21d0faaff558c379e02a325d9707f1df9389df7db07c39d54ae8e8a21050d62?s=96&d=mm&r=g","caption":"service@yellowtie.fr"},"sameAs":["https:\/\/groupe-canopee.yellowtie.fr"]}]}},"_links":{"self":[{"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/posts\/31974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/comments?post=31974"}],"version-history":[{"count":1,"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/posts\/31974\/revisions"}],"predecessor-version":[{"id":31984,"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/posts\/31974\/revisions\/31984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/media\/31977"}],"wp:attachment":[{"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/media?parent=31974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/categories?post=31974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/groupe-canopee.fr\/en\/wp-json\/wp\/v2\/tags?post=31974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}